{"id":3157,"date":"2025-08-12T20:47:13","date_gmt":"2025-08-12T18:47:13","guid":{"rendered":"https:\/\/inclusivesport.ch\/?post_type=projektbeispiele&#038;p=3157"},"modified":"2025-08-27T11:27:59","modified_gmt":"2025-08-27T09:27:59","slug":"dare-forma-allinclusione-nellhockey-universitario-insieme","status":"publish","type":"projektbeispiele","link":"https:\/\/inclusivesport.ch\/it\/projektbeispiele\/inklusion-im-unihockey-gemeinsam-erleben-gestalten\/","title":{"rendered":"Inclusione nell\u2019unihockey \u2013 vivere e creare insieme"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"iawp_total_views":85,"footnotes":""},"projekte-kategorien":[68],"hf_cat_projektbeispiele":[],"class_list":["post-3157","projektbeispiele","type-projektbeispiele","status-publish","hentry","projekte-kategorien-projekte-programme-kooperationen"],"acf":[],"_links":{"self":[{"href":"https:\/\/inclusivesport.ch\/it\/wp-json\/wp\/v2\/projektbeispiele\/3157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inclusivesport.ch\/it\/wp-json\/wp\/v2\/projektbeispiele"}],"about":[{"href":"https:\/\/inclusivesport.ch\/it\/wp-json\/wp\/v2\/types\/projektbeispiele"}],"version-history":[{"count":0,"href":"https:\/\/inclusivesport.ch\/it\/wp-json\/wp\/v2\/projektbeispiele\/3157\/revisions"}],"wp:attachment":[{"href":"https:\/\/inclusivesport.ch\/it\/wp-json\/wp\/v2\/media?parent=3157"}],"wp:term":[{"taxonomy":"projekte-kategorien","embeddable":true,"href":"https:\/\/inclusivesport.ch\/it\/wp-json\/wp\/v2\/projekte-kategorien?post=3157"},{"taxonomy":"hf_cat_projektbeispiele","embeddable":true,"href":"https:\/\/inclusivesport.ch\/it\/wp-json\/wp\/v2\/hf_cat_projektbeispiele?post=3157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}